{"id":761,"date":"2019-10-28T10:26:27","date_gmt":"2019-10-28T13:26:27","guid":{"rendered":"http:\/\/braziliando.96.lt\/?page_id=761"},"modified":"2025-06-24T10:55:37","modified_gmt":"2025-06-24T13:55:37","slug":"braziliando","status":"publish","type":"page","link":"https:\/\/braziliando.com\/pt\/braziliando\/","title":{"rendered":"Braziliando"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"761\" class=\"elementor elementor-761\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b955c5f elementor-section-height-min-height elementor-section-stretched elementor-section-items-top elementor-section-boxed elementor-section-height-default elementor-invisible\" data-id=\"1b955c5f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:1380,&quot;url&quot;:&quot;http:\\\/\\\/braziliando.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Pag_About.jpg&quot;}],&quot;shape_divider_bottom&quot;:&quot;mountains&quot;,&quot;background_slideshow_slide_duration&quot;:6001,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c2196bc\" data-id=\"1c2196bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-423fd93a elementor-widget elementor-widget-heading\" data-id=\"423fd93a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Transforma\u00e7\u00f5es positivas \natrav\u00e9s do turismo sustent\u00e1vel\u200b<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-323be630 elementor-align-center elementor-button-warning elementor-widget elementor-widget-button\" data-id=\"323be630\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs elementor-animation-grow\" href=\"#missao\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-down\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4a8471ba elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"4a8471ba\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ccecfa0\" data-id=\"1ccecfa0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef84cbe elementor-widget elementor-widget-menu-anchor\" data-id=\"ef84cbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"missao\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82cbc2e elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"82cbc2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-007e941 elementor-widget elementor-widget-lae-testimonials-slider\" data-id=\"007e941\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-testimonials-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-testimonials-slider lae-testimonials-slider-style1 lae-container\"\n                                 data-settings='{&quot;fade&quot;:true,&quot;autoplay&quot;:true,&quot;autoplay_speed&quot;:5000,&quot;animation_speed&quot;:600,&quot;dots&quot;:false,&quot;arrows&quot;:false,&quot;pause_on_hover&quot;:false,&quot;pause_on_focus&quot;:false,&quot;adaptive_height&quot;:false,&quot;display_columns&quot;:1,&quot;scroll_columns&quot;:1,&quot;tablet_width&quot;:800,&quot;tablet_display_columns&quot;:1,&quot;tablet_scroll_columns&quot;:1,&quot;mobile_width&quot;:480,&quot;mobile_display_columns&quot;:1,&quot;mobile_scroll_columns&quot;:1}'>\n\n        \n            \n            \n<div class=\"lae-testimonial lae-rating-none\">\n\n    <div class=\"lae-testimonial-text\">\n\n        <i class=\"lae-icon-quote\"><\/i>\n\n        \n        <p><span style=\"color: #54595f;\">Nossa miss\u00e3o \u00e9<\/span><span style=\"color: #00add8;\">\u00a0<\/span>promover possibilidades de transforma\u00e7\u00f5es positivas atrav\u00e9s de experi\u00eancias de viagem aut\u00eanticas e respons\u00e1veis.<\/p>\n    <\/div>\n\n    <div class=\"lae-testimonial-user\">\n\n        <div class=\"lae-image-wrapper\">\n\n            \n            \n                \n            \n        <\/div><!-- .lae-image-wrapper -->\n\n        <div class=\"lae-user-text\">\n\n            <h4 class=\"lae-author-name\"><\/h4>\n\n            <div class=\"lae-author-credentials\"><\/div>\n\n        <\/div>\n\n    <\/div><!-- .lae-testimonial-user -->\n\n<\/div><!-- .lae-testimonial -->\n        \n<\/div><!-- .lae-testimonials-slider -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-629825b elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"629825b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"257\" height=\"30\" data-src=\"https:\/\/braziliando.com\/wp-content\/uploads\/2019\/10\/tribal_black2.png\" class=\"attachment-hestia-blog size-hestia-blog wp-image-390 lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 257px; --smush-placeholder-aspect-ratio: 257\/30;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dd6b8ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dd6b8ca\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ffe2d2\" data-id=\"2ffe2d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49f4233 elementor-widget elementor-widget-testimonial\" data-id=\"49f4233\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">Nossa hist\u00f3ria<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-171bbcb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"171bbcb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-31ce376\" data-id=\"31ce376\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7a1c5b elementor-widget elementor-widget-heading\" data-id=\"a7a1c5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Uma semente amaz\u00f4nica<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-57b71bb\" data-id=\"57b71bb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2612e8 elementor-widget elementor-widget-text-editor\" data-id=\"a2612e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p><p>Em 2016, quando a Ana embarcou com a Tereza, sua m\u00e3e e agora s\u00f3cia, em uma viagem para a Amaz\u00f4nia, se conectou profundamente com a natureza e com a popula\u00e7\u00e3o da regi\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a51792b elementor-widget elementor-widget-text-editor\" data-id=\"a51792b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: inherit;\">Ouvir a hist\u00f3ria de quem nasceu e cresceu na floresta, visitar suas casas e presenciar seus desafios, a motivou a retornar para uma viv\u00eancia diferente.&nbsp;<\/span><span style=\"font-size: inherit;\">Assim, surgiu nossa primeira expedi\u00e7\u00e3o de volunturismo: o Amazoniando<\/span><span style=\"font-family: Montserrat, sans-serif;\">.&nbsp;<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d5312d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d5312d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cb633ba\" data-id=\"cb633ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b7a724c elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b7a724c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3df3c5d\" data-id=\"3df3c5d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fbfe10 elementor-widget elementor-widget-text-editor\" data-id=\"3fbfe10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nessa expedi\u00e7\u00e3o, uma das atividades realizadas foi a \u00c1rvore dos Sonhos.\u00a0<span style=\"font-size: inherit;\">Nela, ouvimos os anseios das mulheres ribeirinhas e ajudamos na constru\u00e7\u00e3o de um plano para realiza\u00e7\u00e3o de um sonho coletivo.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89d1f48 elementor-widget elementor-widget-text-editor\" data-id=\"89d1f48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: inherit;\">Oportunidades de emprego e fontes de renda foram levantadas como necessidades em comum e elas identificaram o turismo como uma solu\u00e7\u00e3o.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8dc689f elementor-widget elementor-widget-text-editor\" data-id=\"8dc689f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: inherit;\">A Braziliando <\/span><span style=\"font-size: inherit;\">ajudou ent\u00e3o na estrutura\u00e7\u00e3o da experi\u00eancia e passou<\/span><span style=\"font-size: inherit;\"> a facilitar a conex\u00e3o de viajantes com a comunidade, buscando valorizar as tradi\u00e7\u00f5es e gerar oportunidades para os comunit\u00e1rios.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9a5eb8 elementor-align-center elementor-button-warning elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"e9a5eb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"http:\/\/braziliando.com\/index.php\/impacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Confira nosso impacto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ffdfa14\" data-id=\"ffdfa14\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-645b785 elementor-widget elementor-widget-heading\" data-id=\"645b785\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">A \u00e1rvore dos sonhos<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4eaa6fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4eaa6fd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d1bd559\" data-id=\"d1bd559\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12bd084 elementor-widget elementor-widget-testimonial\" data-id=\"12bd084\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">Experi\u00eancias<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2924ed27 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2924ed27\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-42e4d5fb\" data-id=\"42e4d5fb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48e7c55f elementor-widget elementor-widget-heading\" data-id=\"48e7c55f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Turismo de Base Comunit\u00e1ria<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-58ed232f\" data-id=\"58ed232f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4862e6da elementor-widget elementor-widget-text-editor\" data-id=\"4862e6da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p><p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Um modo de fazer turismo no qual as atividades s\u00e3o protagonizadas pela pr\u00f3pria comunidade local e que tem como pilar a sustentabilidade (sociocultural, econ\u00f4mica e ambiental). Quem vive essa experi\u00eancia \u00e9 integrado \u00e0 cultura pelos comunit\u00e1rios, que recebem o visitante e apresentam o seu modo de vida.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47e9526 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47e9526\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd48eed\" data-id=\"bd48eed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e0e367b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0e367b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c87f264\" data-id=\"c87f264\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7822b1f1 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7822b1f1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2a92cd56\" data-id=\"2a92cd56\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d77a83f elementor-widget elementor-widget-text-editor\" data-id=\"2d77a83f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span><br><\/span><\/p><p><span>Uma experi\u00eancia que integra uma verdadeira imers\u00e3o na realidade local com o trabalho volunt\u00e1rio, na qual os participantes implementam atividades que visam a contribuir com as comunidades locais ou com a biodiversidade. Buscamos possibilitar transforma\u00e7\u00f5es positivas&nbsp; tanto para os comunit\u00e1rios e seu entorno quanto para os viajantes.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-31af42ec\" data-id=\"31af42ec\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e172ba2 elementor-widget elementor-widget-heading\" data-id=\"7e172ba2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Volunturismo<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ecd1a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ecd1a4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e560853\" data-id=\"e560853\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ab2b34 elementor-section-stretched elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-top elementor-section-height-default\" data-id=\"7ab2b34\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-094ee1d\" data-id=\"094ee1d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abd425b elementor-widget elementor-widget-lae-testimonials-slider\" data-id=\"abd425b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-testimonials-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-testimonials-slider lae-testimonials-slider-style1 lae-container\"\n                                 data-settings='{&quot;fade&quot;:true,&quot;autoplay&quot;:true,&quot;autoplay_speed&quot;:5000,&quot;animation_speed&quot;:600,&quot;dots&quot;:false,&quot;arrows&quot;:false,&quot;pause_on_hover&quot;:false,&quot;pause_on_focus&quot;:false,&quot;adaptive_height&quot;:false,&quot;display_columns&quot;:1,&quot;scroll_columns&quot;:1,&quot;tablet_width&quot;:800,&quot;tablet_display_columns&quot;:1,&quot;tablet_scroll_columns&quot;:1,&quot;mobile_width&quot;:480,&quot;mobile_display_columns&quot;:1,&quot;mobile_scroll_columns&quot;:1}'>\n\n        \n            \n            \n<div class=\"lae-testimonial lae-rating-none\">\n\n    <div class=\"lae-testimonial-text\">\n\n        <i class=\"lae-icon-quote\"><\/i>\n\n        \n        <p>Acreditamos que o turismo pode impulsionar a mudan\u00e7a que queremos ver no mundo.<\/p>\n    <\/div>\n\n    <div class=\"lae-testimonial-user\">\n\n        <div class=\"lae-image-wrapper\">\n\n            \n            \n                \n            \n        <\/div><!-- .lae-image-wrapper -->\n\n        <div class=\"lae-user-text\">\n\n            <h4 class=\"lae-author-name\"><\/h4>\n\n            <div class=\"lae-author-credentials\"><\/div>\n\n        <\/div>\n\n    <\/div><!-- .lae-testimonial-user -->\n\n<\/div><!-- .lae-testimonial -->\n        \n<\/div><!-- .lae-testimonials-slider -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0793b14 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0793b14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"http:\/\/braziliando.com\/index.php\/experiencias\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vamos junt@s<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c45da4a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c45da4a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7a0e8ca1\" data-id=\"7a0e8ca1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-be7a27d\" data-id=\"be7a27d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd43357 elementor-widget elementor-widget-heading\" data-id=\"cd43357\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lideran\u00e7a feminina multigeracional<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22ae42c elementor-widget elementor-widget-text-editor\" data-id=\"22ae42c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201cViajando, vivenciamos contextos sociais e culturais diferentes, nos relacionamos com pessoas de realidades distintas e nos conectamos profundamente com a natureza. Passamos a valorizar a simplicidade e mudamos nossa vis\u00e3o de mundo. Esperamos que as viagens da Braziliando fa\u00e7am o mesmo por voc\u00ea!\u201d<\/p><p><strong>Ana Taranto e Tereza Cristina, S\u00f3cias <\/strong><\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e42f53d\" data-id=\"e42f53d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ccf04d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ccf04d8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aacca08\" data-id=\"aacca08\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9d8e3a elementor-widget elementor-widget-heading\" data-id=\"c9d8e3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conhe\u00e7a o time <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-061a10c elementor-widget-mobile__width-initial elementor-widget elementor-widget-lae-testimonials-slider\" data-id=\"061a10c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lae-testimonials-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"lae-testimonials-slider lae-testimonials-slider-style1 lae-container\"\n                                 data-settings='{&quot;fade&quot;:false,&quot;autoplay&quot;:true,&quot;autoplay_speed&quot;:9000,&quot;animation_speed&quot;:600,&quot;dots&quot;:true,&quot;arrows&quot;:true,&quot;pause_on_hover&quot;:true,&quot;pause_on_focus&quot;:false,&quot;adaptive_height&quot;:false,&quot;display_columns&quot;:1,&quot;scroll_columns&quot;:1,&quot;tablet_width&quot;:800,&quot;tablet_display_columns&quot;:1,&quot;tablet_scroll_columns&quot;:1,&quot;mobile_width&quot;:480,&quot;mobile_display_columns&quot;:1,&quot;mobile_scroll_columns&quot;:1}'>\n\n        \n            \n            \n<div class=\"lae-testimonial lae-rating-none\">\n\n    <div class=\"lae-testimonial-text\">\n\n        <i class=\"lae-icon-quote\"><\/i>\n\n        \n        <p style=\"text-align: center;\">Formada em Administra\u00e7\u00e3o pela UFRJ e com MBA em Marketing pela FGV, decidiu fundar a Braziliando em mar\u00e7o de 2016. Participou das aulas de Princ\u00edpios de Sustentabilidade e Impacto Social Estrat\u00e9gico da <a href=\"https:\/\/www.uclaextension.edu\">UCLA<\/a>, dos m\u00f3dulos Econ\u00f4mico, Ecol\u00f3gico e Vis\u00e3o de Mundo do <a href=\"https:\/\/www.gaiaeducation.org\">Gaia Education<\/a>, do curso Multiplicadores de Turismo de Base Comunit\u00e1ria do <a href=\"https:\/\/www.mamiraua.org.br\">Instituto Mamirau\u00e1<\/a> e de Teoria U da <a href=\"https:\/\/www.basecolaborativa.org\">Base Colaborativa<\/a>. Al\u00e9m de ter liderado o Marketing de uma multinacional de recrutamento, teve experi\u00eancia no setor em empresas como L\u2019Or\u00e9al e Oi.<\/p>\n    <\/div>\n\n    <div class=\"lae-testimonial-user\">\n\n        <div class=\"lae-image-wrapper\">\n\n            \n            \n                <img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/braziliando.com\/wp-content\/uploads\/2025\/04\/Untitled-1-150x150.png\" class=\"lae-image full lazyload\" alt=\"\" data-srcset=\"https:\/\/braziliando.com\/wp-content\/uploads\/2025\/04\/Untitled-1-150x150.png 150w, https:\/\/braziliando.com\/wp-content\/uploads\/2025\/04\/Untitled-1-300x300.png 300w, https:\/\/braziliando.com\/wp-content\/uploads\/2025\/04\/Untitled-1-1024x1024.png 1024w, https:\/\/braziliando.com\/wp-content\/uploads\/2025\/04\/Untitled-1-768x768.png 768w, https:\/\/braziliando.com\/wp-content\/uploads\/2025\/04\/Untitled-1-12x12.png 12w, https:\/\/braziliando.com\/wp-content\/uploads\/2025\/04\/Untitled-1.png 1080w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/>\n            \n        <\/div><!-- .lae-image-wrapper -->\n\n        <div class=\"lae-user-text\">\n\n            <h4 class=\"lae-author-name\">Ana Taranto<\/h4>\n\n            <div class=\"lae-author-credentials\">S\u00f3cia fundadora \/ Marketing &amp; Comercial<\/div>\n\n        <\/div>\n\n    <\/div><!-- .lae-testimonial-user -->\n\n<\/div><!-- .lae-testimonial -->\n        \n            \n            \n<div class=\"lae-testimonial lae-rating-none\">\n\n    <div class=\"lae-testimonial-text\">\n\n        <i class=\"lae-icon-quote\"><\/i>\n\n        \n        <p style=\"text-align: center;\">Formada em Letras, foi professora e, depois, S\u00f3cia e Diretora na Transceiver. Ap\u00f3s se envolver e apoiar a Braziliando de diversas formas, aceitou o convite para se tornar s\u00f3cia da empresa em 2018. Participou do EMPRETEC, desenvolvido pela ONU e ministrado pelo SEBRAE, do Curso de Desenvolvimento Empresarial (IDE-Brasil),\u00a0 do Experi\u00eancias e olhares sobre o Turismo de Base Comunit\u00e1ria (do CPF-SESC-SP).<\/p>\n    <\/div>\n\n    <div class=\"lae-testimonial-user\">\n\n        <div class=\"lae-image-wrapper\">\n\n            \n            \n                <img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/braziliando.com\/wp-content\/uploads\/2025\/04\/Untitled-2-150x150.png\" class=\"lae-image full lazyload\" alt=\"\" data-srcset=\"https:\/\/braziliando.com\/wp-content\/uploads\/2025\/04\/Untitled-2-150x150.png 150w, https:\/\/braziliando.com\/wp-content\/uploads\/2025\/04\/Untitled-2-300x300.png 300w, https:\/\/braziliando.com\/wp-content\/uploads\/2025\/04\/Untitled-2-1024x1024.png 1024w, https:\/\/braziliando.com\/wp-content\/uploads\/2025\/04\/Untitled-2-768x768.png 768w, https:\/\/braziliando.com\/wp-content\/uploads\/2025\/04\/Untitled-2-12x12.png 12w, https:\/\/braziliando.com\/wp-content\/uploads\/2025\/04\/Untitled-2.png 1080w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/>\n            \n        <\/div><!-- .lae-image-wrapper -->\n\n        <div class=\"lae-user-text\">\n\n            <h4 class=\"lae-author-name\">Tereza Cristina<\/h4>\n\n            <div class=\"lae-author-credentials\">S\u00f3cia \/ Administrativo &amp; Financeiro<\/div>\n\n        <\/div>\n\n    <\/div><!-- .lae-testimonial-user -->\n\n<\/div><!-- .lae-testimonial -->\n        \n<\/div><!-- .lae-testimonials-slider -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58d67857 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58d67857\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4605b905\" data-id=\"4605b905\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f239b0f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3f239b0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg elementor-animation-grow\" href=\"http:\/\/braziliando.com\/index.php\/experiencias\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Conhe\u00e7a as experi\u00eancias<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2da0045c elementor-section-height-min-height elementor-section-full_width elementor-section-height-default elementor-section-items-middle\" data-id=\"2da0045c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-1cddb4a8\" data-id=\"1cddb4a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b719d40 elementor-widget elementor-widget-image\" data-id=\"2b719d40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hub.wtm.com\/pt\/artigos\/turismo-responsavel\/os-ganhadores-do-wtm-latin-america-responsible-tourism-awards-mostram-que-desenvolvimento-sustentavel-e-a-grande-tendencia-do-setor-de-viagens-e-turismo\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"909\" height=\"274\" data-src=\"https:\/\/braziliando.com\/wp-content\/uploads\/2025\/05\/WhatsApp_Image_2025-05-21_at_16.40.13-removebg-preview.png\" class=\"attachment-full size-full wp-image-7417 lazyload\" alt=\"\" data-srcset=\"https:\/\/braziliando.com\/wp-content\/uploads\/2025\/05\/WhatsApp_Image_2025-05-21_at_16.40.13-removebg-preview.png 909w, https:\/\/braziliando.com\/wp-content\/uploads\/2025\/05\/WhatsApp_Image_2025-05-21_at_16.40.13-removebg-preview-300x90.png 300w, https:\/\/braziliando.com\/wp-content\/uploads\/2025\/05\/WhatsApp_Image_2025-05-21_at_16.40.13-removebg-preview-768x231.png 768w, https:\/\/braziliando.com\/wp-content\/uploads\/2025\/05\/WhatsApp_Image_2025-05-21_at_16.40.13-removebg-preview-18x5.png 18w\" data-sizes=\"(max-width: 909px) 100vw, 909px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 909px; --smush-placeholder-aspect-ratio: 909\/274;\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-480f0504\" data-id=\"480f0504\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d87f81c elementor-widget elementor-widget-image\" data-id=\"6d87f81c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/drive.google.com\/file\/d\/12Agy2H5r3dcfPRMIEI0DdtVnMUhQUsN2\/view?usp=sharing\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"600\" data-src=\"https:\/\/braziliando.com\/wp-content\/uploads\/2022\/07\/2836-1.png\" class=\"attachment-full size-full wp-image-3226 lazyload\" alt=\"\" data-srcset=\"https:\/\/braziliando.com\/wp-content\/uploads\/2022\/07\/2836-1.png 600w, https:\/\/braziliando.com\/wp-content\/uploads\/2022\/07\/2836-1-160x160.png 160w, https:\/\/braziliando.com\/wp-content\/uploads\/2022\/07\/2836-1-300x300.png 300w, https:\/\/braziliando.com\/wp-content\/uploads\/2022\/07\/2836-1-150x150.png 150w, https:\/\/braziliando.com\/wp-content\/uploads\/2022\/07\/2836-1-12x12.png 12w, https:\/\/braziliando.com\/wp-content\/uploads\/2022\/07\/elementor\/thumbs\/2836-1-ps1jf48uaratbffog2797fi59fujbwrzzhpgeqsjqg.png 100w, https:\/\/braziliando.com\/wp-content\/uploads\/2022\/07\/elementor\/thumbs\/2836-1-ps1jf48wz8myv1dw5o3tusyjjl44drukxfstxtufsw.png 320w, https:\/\/braziliando.com\/wp-content\/uploads\/2022\/07\/elementor\/thumbs\/2836-1-ps1jf48vrduj9185qr8nqq46i8whq0mv1n7nsfd7rs.png 220w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/600;\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-3003728e\" data-id=\"3003728e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16d5b981 elementor-widget elementor-widget-image\" data-id=\"16d5b981\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/drive.google.com\/file\/d\/1GQ8zaI8iojTRNY0afs9NAWzwJCa7_Dq8\/view?usp=sharing\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"412\" height=\"392\" data-src=\"https:\/\/braziliando.com\/wp-content\/uploads\/2023\/04\/united_earth-green_logo.png\" class=\"attachment-full size-full wp-image-4663 lazyload\" alt=\"\" data-srcset=\"https:\/\/braziliando.com\/wp-content\/uploads\/2023\/04\/united_earth-green_logo.png 412w, https:\/\/braziliando.com\/wp-content\/uploads\/2023\/04\/united_earth-green_logo-300x285.png 300w, https:\/\/braziliando.com\/wp-content\/uploads\/2023\/04\/united_earth-green_logo-13x12.png 13w\" data-sizes=\"(max-width: 412px) 100vw, 412px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 412px; --smush-placeholder-aspect-ratio: 412\/392;\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-3357e665\" data-id=\"3357e665\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9f2a7d elementor-widget elementor-widget-image\" data-id=\"c9f2a7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/coletivomuda.tur.br\/experiencia\/braziliando\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"388\" height=\"333\" data-src=\"https:\/\/braziliando.com\/wp-content\/uploads\/2025\/06\/selo-fundo-verde-escuro.svg\" class=\"attachment-full size-full wp-image-7431 lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 388px; --smush-placeholder-aspect-ratio: 388\/333;\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-584517d9\" data-id=\"584517d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ab6e6c4 elementor-widget elementor-widget-image\" data-id=\"4ab6e6c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.iniciativajovem.org.br\/site\/rede-de-empreendimentos-sustentaveis\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2160\" height=\"1080\" data-src=\"https:\/\/braziliando.com\/wp-content\/uploads\/2025\/05\/SELO_1.png\" class=\"attachment-full size-full wp-image-7419 lazyload\" alt=\"\" data-srcset=\"https:\/\/braziliando.com\/wp-content\/uploads\/2025\/05\/SELO_1.png 2160w, https:\/\/braziliando.com\/wp-content\/uploads\/2025\/05\/SELO_1-300x150.png 300w, https:\/\/braziliando.com\/wp-content\/uploads\/2025\/05\/SELO_1-1024x512.png 1024w, https:\/\/braziliando.com\/wp-content\/uploads\/2025\/05\/SELO_1-768x384.png 768w, https:\/\/braziliando.com\/wp-content\/uploads\/2025\/05\/SELO_1-1536x768.png 1536w, https:\/\/braziliando.com\/wp-content\/uploads\/2025\/05\/SELO_1-2048x1024.png 2048w, https:\/\/braziliando.com\/wp-content\/uploads\/2025\/05\/SELO_1-18x9.png 18w\" data-sizes=\"(max-width: 2160px) 100vw, 2160px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2160px; --smush-placeholder-aspect-ratio: 2160\/1080;\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-54f378d9\" data-id=\"54f378d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d4c768e elementor-widget elementor-widget-image\" data-id=\"3d4c768e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/drive.google.com\/file\/d\/196Oq7KmPtYJ8SReiBaQZhYlD4hg-ac7D\/view?usp=sharing\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"67\" data-src=\"https:\/\/braziliando.com\/wp-content\/uploads\/2019\/10\/logoCadastur_marca-negativa-300x67.png\" class=\"attachment-medium size-medium wp-image-392 lazyload\" alt=\"\" data-srcset=\"https:\/\/braziliando.com\/wp-content\/uploads\/2019\/10\/logoCadastur_marca-negativa-300x67.png 300w, https:\/\/braziliando.com\/wp-content\/uploads\/2019\/10\/logoCadastur_marca-negativa.png 490w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/67;\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Transforma\u00e7\u00f5es positivas atrav\u00e9s do turismo sustent\u00e1vel\u200b Nossa miss\u00e3o \u00e9\u00a0promover possibilidades de transforma\u00e7\u00f5es positivas atrav\u00e9s de experi\u00eancias de viagem aut\u00eanticas e respons\u00e1veis. Nossa hist\u00f3ria Uma semente amaz\u00f4nica Em 2016, quando a Ana embarcou com a Tereza, sua m\u00e3e e agora s\u00f3cia, em uma viagem para a Amaz\u00f4nia, se conectou profundamente com<\/p>\n","protected":false},"author":1,"featured_media":1380,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_eb_attr":"","footnotes":""},"class_list":["post-761","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Braziliando - Braziliando<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/braziliando.com\/pt\/braziliando\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Braziliando - Braziliando\" \/>\n<meta property=\"og:description\" content=\"Transforma\u00e7\u00f5es positivas atrav\u00e9s do turismo sustent\u00e1vel\u200b Nossa miss\u00e3o \u00e9\u00a0promover possibilidades de transforma\u00e7\u00f5es positivas atrav\u00e9s de experi\u00eancias de viagem aut\u00eanticas e respons\u00e1veis. Nossa hist\u00f3ria Uma semente amaz\u00f4nica Em 2016, quando a Ana embarcou com a Tereza, sua m\u00e3e e agora s\u00f3cia, em uma viagem para a Amaz\u00f4nia, se conectou profundamente com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/braziliando.com\/pt\/braziliando\/\" \/>\n<meta property=\"og:site_name\" content=\"Braziliando\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/braziliando\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-24T13:55:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/braziliando.com\/wp-content\/uploads\/2019\/11\/Pag_About.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"801\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/braziliando.com\\\/braziliando\\\/\",\"url\":\"https:\\\/\\\/braziliando.com\\\/braziliando\\\/\",\"name\":\"Braziliando - Braziliando\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/braziliando.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/braziliando.com\\\/braziliando\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/braziliando.com\\\/braziliando\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/braziliando.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Pag_About.jpg\",\"datePublished\":\"2019-10-28T13:26:27+00:00\",\"dateModified\":\"2025-06-24T13:55:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/braziliando.com\\\/braziliando\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/braziliando.com\\\/braziliando\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/braziliando.com\\\/braziliando\\\/#primaryimage\",\"url\":\"https:\\\/\\\/braziliando.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Pag_About.jpg\",\"contentUrl\":\"https:\\\/\\\/braziliando.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Pag_About.jpg\",\"width\":1200,\"height\":801,\"caption\":\"Turismo Sustent\u00e1vel na Amaz\u00f4nia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/braziliando.com\\\/braziliando\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/braziliando.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Braziliando\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/braziliando.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/braziliando.com\\\/en\\\/\",\"name\":\"Braziliando - Viagens aut\u00eanticas e transformadoras\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/braziliando.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/braziliando.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/braziliando.com\\\/en\\\/#organization\",\"name\":\"Braziliando\",\"url\":\"https:\\\/\\\/braziliando.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/braziliando.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/braziliando.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Logo-BRDO-atualizada-fundo-transparente.png\",\"contentUrl\":\"https:\\\/\\\/braziliando.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Logo-BRDO-atualizada-fundo-transparente.png\",\"width\":452,\"height\":262,\"caption\":\"Braziliando\"},\"image\":{\"@id\":\"https:\\\/\\\/braziliando.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/braziliando\\\/\",\"https:\\\/\\\/www.instagram.com\\\/brazilian.do\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Braziliando - Braziliando","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/braziliando.com\/pt\/braziliando\/","og_locale":"pt_BR","og_type":"article","og_title":"Braziliando - Braziliando","og_description":"Transforma\u00e7\u00f5es positivas atrav\u00e9s do turismo sustent\u00e1vel\u200b Nossa miss\u00e3o \u00e9\u00a0promover possibilidades de transforma\u00e7\u00f5es positivas atrav\u00e9s de experi\u00eancias de viagem aut\u00eanticas e respons\u00e1veis. Nossa hist\u00f3ria Uma semente amaz\u00f4nica Em 2016, quando a Ana embarcou com a Tereza, sua m\u00e3e e agora s\u00f3cia, em uma viagem para a Amaz\u00f4nia, se conectou profundamente com","og_url":"https:\/\/braziliando.com\/pt\/braziliando\/","og_site_name":"Braziliando","article_publisher":"https:\/\/www.facebook.com\/braziliando\/","article_modified_time":"2025-06-24T13:55:37+00:00","og_image":[{"width":1200,"height":801,"url":"https:\/\/braziliando.com\/wp-content\/uploads\/2019\/11\/Pag_About.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/braziliando.com\/braziliando\/","url":"https:\/\/braziliando.com\/braziliando\/","name":"Braziliando - Braziliando","isPartOf":{"@id":"https:\/\/braziliando.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/braziliando.com\/braziliando\/#primaryimage"},"image":{"@id":"https:\/\/braziliando.com\/braziliando\/#primaryimage"},"thumbnailUrl":"https:\/\/braziliando.com\/wp-content\/uploads\/2019\/11\/Pag_About.jpg","datePublished":"2019-10-28T13:26:27+00:00","dateModified":"2025-06-24T13:55:37+00:00","breadcrumb":{"@id":"https:\/\/braziliando.com\/braziliando\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/braziliando.com\/braziliando\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/braziliando.com\/braziliando\/#primaryimage","url":"https:\/\/braziliando.com\/wp-content\/uploads\/2019\/11\/Pag_About.jpg","contentUrl":"https:\/\/braziliando.com\/wp-content\/uploads\/2019\/11\/Pag_About.jpg","width":1200,"height":801,"caption":"Turismo Sustent\u00e1vel na Amaz\u00f4nia"},{"@type":"BreadcrumbList","@id":"https:\/\/braziliando.com\/braziliando\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/braziliando.com\/"},{"@type":"ListItem","position":2,"name":"Braziliando"}]},{"@type":"WebSite","@id":"https:\/\/braziliando.com\/en\/#website","url":"https:\/\/braziliando.com\/en\/","name":"Braziliando - Viagens aut\u00eanticas e transformadoras","description":"","publisher":{"@id":"https:\/\/braziliando.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/braziliando.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/braziliando.com\/en\/#organization","name":"Braziliando","url":"https:\/\/braziliando.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/braziliando.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/braziliando.com\/wp-content\/uploads\/2019\/10\/Logo-BRDO-atualizada-fundo-transparente.png","contentUrl":"https:\/\/braziliando.com\/wp-content\/uploads\/2019\/10\/Logo-BRDO-atualizada-fundo-transparente.png","width":452,"height":262,"caption":"Braziliando"},"image":{"@id":"https:\/\/braziliando.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/braziliando\/","https:\/\/www.instagram.com\/brazilian.do\/"]}]}},"_links":{"self":[{"href":"https:\/\/braziliando.com\/pt\/wp-json\/wp\/v2\/pages\/761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/braziliando.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/braziliando.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/braziliando.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/braziliando.com\/pt\/wp-json\/wp\/v2\/comments?post=761"}],"version-history":[{"count":58,"href":"https:\/\/braziliando.com\/pt\/wp-json\/wp\/v2\/pages\/761\/revisions"}],"predecessor-version":[{"id":7449,"href":"https:\/\/braziliando.com\/pt\/wp-json\/wp\/v2\/pages\/761\/revisions\/7449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/braziliando.com\/pt\/wp-json\/wp\/v2\/media\/1380"}],"wp:attachment":[{"href":"https:\/\/braziliando.com\/pt\/wp-json\/wp\/v2\/media?parent=761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}