{"id":6162,"date":"2023-12-28T12:59:45","date_gmt":"2023-12-28T15:59:45","guid":{"rendered":"https:\/\/braziliando.com\/?p=6162"},"modified":"2023-12-28T12:59:46","modified_gmt":"2023-12-28T15:59:46","slug":"retrospectiva-2023","status":"publish","type":"post","link":"https:\/\/braziliando.com\/pt\/2023\/12\/28\/retrospectiva-2023\/","title":{"rendered":"Retrospectiva Braziliando 2023"},"content":{"rendered":"\n<p class=\"has-text-align-center\">Mais um ciclo que se encerra e viemos celebrar as conquistas, os aprendizados e as pessoas que fizeram parte desse ano especial. Em 2023, recebemos um pr\u00eamio in\u00e9dito, participamos de programas inspiradores, espalhamos nossas sementes em um novo destino e promovemos encontros marcantes. Vem conferir tudo o que rolou na Retrospectiva Braziliando!<\/p>\n\n\n\n<p>O ano come\u00e7ou com uma grande surpresa: fomos premiadas com o <a href=\"https:\/\/braziliando.com\/pt\/2023\/03\/09\/braziliando-conquista-nobel-verde\/\" target=\"_blank\" rel=\"noreferrer noopener\">United Earth Amazonia Award<\/a>, o Nobel Verde. Al\u00e9m da emo\u00e7\u00e3o e felicidade em recebermos essa conquista, a noite da premia\u00e7\u00e3o tamb\u00e9m foi uma oportunidade de reafirmarmos nosso compromisso com a sustentabilidade e de celebrarmos com pessoas da comunidade e outros parceiros que ajudaram a construir a nossa hist\u00f3ria.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/braziliando.com\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-17-at-16.59.49-1024x576.jpeg\" alt=\"\" class=\"wp-image-4560\" srcset=\"https:\/\/braziliando.com\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-17-at-16.59.49-1024x576.jpeg 1024w, https:\/\/braziliando.com\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-17-at-16.59.49-300x169.jpeg 300w, https:\/\/braziliando.com\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-17-at-16.59.49-768x432.jpeg 768w, https:\/\/braziliando.com\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-17-at-16.59.49-1536x864.jpeg 1536w, https:\/\/braziliando.com\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-17-at-16.59.49-18x10.jpeg 18w, https:\/\/braziliando.com\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-17-at-16.59.49-600x338.jpeg 600w, https:\/\/braziliando.com\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-17-at-16.59.49.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Fizemos conex\u00f5es com pessoas, neg\u00f3cios e empresas que nos ajudaram a fortalecer nossa ess\u00eancia e contribu\u00edram com nossa trajet\u00f3ria. A Braziliando foi um dos neg\u00f3cios mentorados no <strong>Programa Inova\u00e7\u00e3o Social para a Amaz\u00f4nia<\/strong>, realizado pelo Portal do Impacto e a Phomenta. Nossa s\u00f3cia-fundadora, Ana Taranto, se inscreveu para o programa e passou por uma capacita\u00e7\u00e3o online. Das quase 300 pessoas que se inscreveram, apenas 10 com melhor engajamento e participa\u00e7\u00e3o foram selecionadas para receber mentorias individuais. Foi uma experi\u00eancia enriquecedora, que nos permitiu ter novos olhares e ampliar nossa rede de contatos.<\/p>\n\n\n\n<p>Tamb\u00e9m fomos aprovadas para a primeira fase do programa de acelera\u00e7\u00e3o <a href=\"https:\/\/100labsbrasil.ambev.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">100+ Labs Brasil<\/a>, uma iniciativa da Ambev em parceria com a Parceiros pela Amaz\u00f4nia e USAID (Ag\u00eancia dos Estados Unidos para o Desenvolvimento Internacional) e executada pelo Quintessa, que une inova\u00e7\u00e3o e sustentabilidade. E agora, no final do ano, tamb\u00e9m fomos aprovadas na <a href=\"https:\/\/inovacao.embraturlab.com.br\/aceleracao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Acelera\u00e7\u00e3o EmbraturLAB #2<\/a>! O programa de inova\u00e7\u00e3o \u00e9 realizado pelo Turistech Hub, o hub l\u00edder em inova\u00e7\u00e3o no turismo brasileiro, e pela EmbraturLAB, o bra\u00e7o de inova\u00e7\u00e3o da Embratur.<\/p>\n\n\n\n<p>Nossa s\u00f3cia, Tereza Taranto, tamb\u00e9m se conectou com importantes institui\u00e7\u00f5es que atuam na regi\u00e3o amaz\u00f4nica. Em uma <a href=\"https:\/\/www.instagram.com\/p\/CurYi_3R4nu\/\" target=\"_blank\" rel=\"noreferrer noopener\">visita de campo<\/a> muito especial, T\u00ea se reuniu com nossos parceiros ind\u00edgenas para tra\u00e7ar o planejamento da viv\u00eancia Amaz\u00f4nia Bar\u00e9 e conheceu novas comunidades e hist\u00f3rias.<\/p>\n\n\n\n<p>Tivemos alguns encontros especiais neste ano! \ud83d\ude4c Em abril, nos reunimos na \u201ccidade maravilhosa\u201d pra percorrer a trilha ind\u00edgena do Jardim Bot\u00e2nico. Por l\u00e1 vimos v\u00e1rias esp\u00e9cies de plantas presentes no cotidiano dos povos origin\u00e1rios, como Sama\u00fama, Manac\u00e1 e Vit\u00f3ria-R\u00e9gia, e ainda curtimos um momento de confraterniza\u00e7\u00e3o. Em 2023, tamb\u00e9m teve o <a href=\"https:\/\/www.instagram.com\/p\/Cu1sthzOoKn\/?img_index=1\" target=\"_blank\" rel=\"noreferrer noopener\">Braziliando Cozinha<\/a>! Juntamos virtualmente o nosso time pra fazer uma moqueca de banana e um delicioso pav\u00ea de frutas. Qual ser\u00e1 nossa pr\u00f3xima aventura gastron\u00f4mica?<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/braziliando.com\/wp-content\/uploads\/2023\/12\/97d9ca20-413d-4b94-a45b-e9a7b8b4859a_Easy-Resize.com_-1024x768.jpg\" alt=\"\" class=\"wp-image-6169 lazyload\" data-srcset=\"https:\/\/braziliando.com\/wp-content\/uploads\/2023\/12\/97d9ca20-413d-4b94-a45b-e9a7b8b4859a_Easy-Resize.com_-1024x768.jpg 1024w, https:\/\/braziliando.com\/wp-content\/uploads\/2023\/12\/97d9ca20-413d-4b94-a45b-e9a7b8b4859a_Easy-Resize.com_-300x225.jpg 300w, https:\/\/braziliando.com\/wp-content\/uploads\/2023\/12\/97d9ca20-413d-4b94-a45b-e9a7b8b4859a_Easy-Resize.com_-768x576.jpg 768w, https:\/\/braziliando.com\/wp-content\/uploads\/2023\/12\/97d9ca20-413d-4b94-a45b-e9a7b8b4859a_Easy-Resize.com_-16x12.jpg 16w, https:\/\/braziliando.com\/wp-content\/uploads\/2023\/12\/97d9ca20-413d-4b94-a45b-e9a7b8b4859a_Easy-Resize.com_.jpg 1280w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><\/figure>\n\n\n\n<p>E as campanhas de 2023?! Quem nos acompanha no <a href=\"https:\/\/www.instagram.com\/brazilian.do\/\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a> viu nossa miss\u00e3o de retirar o pl\u00e1stico de uso \u00fanico da nossa rotina na Semana Sem Pl\u00e1stico, pra mostrar que <a href=\"https:\/\/braziliando.com\/pt\/2023\/07\/24\/julho-sem-plastico-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">#NossoPlanetaN\u00e3o\u00c9Descart\u00e1vel<\/a>. Tamb\u00e9m <a href=\"https:\/\/braziliando.com\/pt\/2023\/06\/28\/semana-do-orgulho-viagem-e-diversidade\/\" target=\"_blank\" rel=\"noreferrer noopener\">falamos sobre diversidade e inclus\u00e3o<\/a> na Semana do Orgulho, com direito a <a href=\"https:\/\/www.instagram.com\/p\/CuHrLRKOr-R\/\" target=\"_blank\" rel=\"noreferrer noopener\">roda de conversa virtual<\/a> e muita reflex\u00e3o!<\/p>\n\n\n\n<p>Outra a\u00e7\u00e3o importante foi a <a href=\"https:\/\/braziliando.com\/pt\/experiencias\/conexao-bare-seca-na-amazonia\/\" target=\"_blank\" rel=\"noreferrer noopener\">Conex\u00e3o Bar\u00e9 Seca Amaz\u00f4nica<\/a>, que alertou sobre a forte estiagem no Amazonas e arrecadou doa\u00e7\u00f5es para nossos parceiros ind\u00edgenas Bar\u00e9. Por causa da seca, a viv\u00eancia <a href=\"https:\/\/braziliando.com\/pt\/turismo-de-base-comunitaria\/\" target=\"_blank\" rel=\"noreferrer noopener\">Amaz\u00f4nia Bar\u00e9<\/a> precisou ser suspensa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" data-src=\"https:\/\/braziliando.com\/wp-content\/uploads\/2023\/10\/IMG-20231005-WA0016-768x1024.jpg\" alt=\"\" class=\"wp-image-5413 lazyload\" data-srcset=\"https:\/\/braziliando.com\/wp-content\/uploads\/2023\/10\/IMG-20231005-WA0016-768x1024.jpg 768w, https:\/\/braziliando.com\/wp-content\/uploads\/2023\/10\/IMG-20231005-WA0016-225x300.jpg 225w, https:\/\/braziliando.com\/wp-content\/uploads\/2023\/10\/IMG-20231005-WA0016-9x12.jpg 9w, https:\/\/braziliando.com\/wp-content\/uploads\/2023\/10\/IMG-20231005-WA0016.jpg 960w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/1024;\" \/><\/figure>\n\n\n\n<p>Neste ano, tamb\u00e9m conseguimos realizar um desejo antigo de <a href=\"https:\/\/braziliando.com\/pt\/2023\/11\/09\/nova-vivencia-quilombola\/\" target=\"_blank\" rel=\"noreferrer noopener\">atuar em outras regi\u00f5es e com novas comunidades<\/a>. Atravessando o Brasil, rumo a Mata Atl\u00e2ntica, realizamos o nosso encontro de equipe no feriado da Consci\u00eancia Negra em um quilombo. Apesar de conhecermos a regi\u00e3o h\u00e1 bastante tempo, foi em 2022 que a Ana conheceu a comunidade e desde ent\u00e3o come\u00e7amos a desenhar essa parceria.<\/p>\n\n\n\n<p>Junto com uma historiadora antirracista, Odara Philomena, vivemos uma imers\u00e3o em um quilombo com mais de 200 anos de hist\u00f3ria e resist\u00eancia. Al\u00e9m da comunidade ter conduzido atividades culturais e na natureza para a gente imergir no seu modo de vida, Odara trouxe questionamentos que contribu\u00edram para a valoriza\u00e7\u00e3o da cultura negra e a quebra de preconceitos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/braziliando.com\/wp-content\/uploads\/2023\/11\/IMG_0372_Easy-Resize.com_-1024x768.jpg\" alt=\"\" class=\"wp-image-5960 lazyload\" data-srcset=\"https:\/\/braziliando.com\/wp-content\/uploads\/2023\/11\/IMG_0372_Easy-Resize.com_-1024x768.jpg 1024w, https:\/\/braziliando.com\/wp-content\/uploads\/2023\/11\/IMG_0372_Easy-Resize.com_-300x225.jpg 300w, https:\/\/braziliando.com\/wp-content\/uploads\/2023\/11\/IMG_0372_Easy-Resize.com_-768x576.jpg 768w, https:\/\/braziliando.com\/wp-content\/uploads\/2023\/11\/IMG_0372_Easy-Resize.com_-16x12.jpg 16w, https:\/\/braziliando.com\/wp-content\/uploads\/2023\/11\/IMG_0372_Easy-Resize.com_.jpg 1280w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><\/figure>\n\n\n\n<p>A <a href=\"https:\/\/braziliando.com\/pt\/experiencias\/vivencia-no-quilombo\/\" target=\"_blank\" rel=\"noreferrer noopener\">Viv\u00eancia no Quilombo<\/a> \u00e9 uma experi\u00eancia transformadora e j\u00e1 tem data para acontecer em 2024 \u2013 de 30\/05 a 02\/06. Nessa imers\u00e3o, voc\u00ea escuta as hist\u00f3rias da comunidade, prova as del\u00edcias da regi\u00e3o, mergulha no rio e caminha em meio a Mata Atl\u00e2ntica, participa de oficinas e at\u00e9 de uma roda de jongo! Preencha a ficha de interesse para receber mais informa\u00e7\u00f5es!<\/p>\n\n\n\n<p>E voc\u00ea tamb\u00e9m pode embarcar \u2013 em qualquer \u00e9poca do ano e sem a necessidade de fechar um grupo \u2013 na viv\u00eancia <a href=\"https:\/\/braziliando.com\/pt\/turismo-de-base-comunitaria\/\" target=\"_blank\" rel=\"noreferrer noopener\">Amaz\u00f4nia Bar\u00e9<\/a>. Nessa jornada pela floresta e a cultura ind\u00edgena, voc\u00ea se hospeda em uma pousada familiar, vivencia atividades do dia a dia local (como navegar de canoa ou caminhar pela mata), ouve as hist\u00f3rias e entra em contato com a sabedoria ancestral dos Bar\u00e9.<\/p>\n\n\n\n<p>Nossa gratid\u00e3o a todas as pessoas que fizeram parte desses momentos e que fazem parte da nossa hist\u00f3ria. Neste ano, a Braziliando completou 7 anos de exist\u00eancia e nossa trajet\u00f3ria n\u00e3o seria a mesma sem as parcerias que constru\u00edmos nesse caminho.<\/p>\n\n\n\n<p>Nosso desejo para o pr\u00f3ximo ano? Continuar promovendo a mudan\u00e7a que queremos ver no mundo! Bora com a gente nessa miss\u00e3o?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mais um ciclo que se encerra e viemos celebrar as conquistas, os aprendizados e as pessoas que fizeram parte desse ano especial. Em 2023, recebemos um pr\u00eamio in\u00e9dito, participamos de programas inspiradores, espalhamos nossas sementes em um novo destino e promovemos encontros marcantes. Vem conferir tudo o que rolou na<\/p>\n","protected":false},"author":3,"featured_media":6170,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[41,33,37,1,26,24],"tags":[20,66,34,14,29],"class_list":["post-6162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-amazonia","category-braziliando","category-diversidade-e-inclusao","category-sem-categoria","category-sustentabilidade","category-tbc","tag-amazonia","tag-comunidade-tradicional","tag-diversidade","tag-indigenas","tag-turismo-sustentavel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Retrospectiva Braziliando 2023 - Braziliando<\/title>\n<meta name=\"description\" content=\"Vem conferir a Retrospectiva de 2023, celebrar com a gente o encerramento deste ciclo e renovar os votos para o pr\u00f3ximo ano.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/braziliando.com\/pt\/2023\/12\/28\/retrospectiva-2023\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retrospectiva Braziliando 2023 - Braziliando\" \/>\n<meta property=\"og:description\" content=\"Vem conferir a Retrospectiva de 2023, celebrar com a gente o encerramento deste ciclo e renovar os votos para o pr\u00f3ximo ano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/braziliando.com\/pt\/2023\/12\/28\/retrospectiva-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Braziliando\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/braziliando\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-28T15:59:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-28T15:59:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/braziliando.com\/wp-content\/uploads\/2023\/12\/Artes-SiteE-mail-mkt_Easy-Resize.com_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Braziliando\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Braziliando\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/braziliando.com\\\/2023\\\/12\\\/28\\\/retrospectiva-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/braziliando.com\\\/2023\\\/12\\\/28\\\/retrospectiva-2023\\\/\"},\"author\":{\"name\":\"Braziliando\",\"@id\":\"https:\\\/\\\/braziliando.com\\\/en\\\/#\\\/schema\\\/person\\\/03deb579256404d78a2b7c1ae1ffa7e6\"},\"headline\":\"Retrospectiva Braziliando 2023\",\"datePublished\":\"2023-12-28T15:59:45+00:00\",\"dateModified\":\"2023-12-28T15:59:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/braziliando.com\\\/2023\\\/12\\\/28\\\/retrospectiva-2023\\\/\"},\"wordCount\":893,\"publisher\":{\"@id\":\"https:\\\/\\\/braziliando.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/braziliando.com\\\/2023\\\/12\\\/28\\\/retrospectiva-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/braziliando.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Artes-SiteE-mail-mkt_Easy-Resize.com_.jpg\",\"keywords\":[\"Amaz\u00f4nia\",\"comunidade tradicional\",\"diversidade\",\"ind\u00edgenas\",\"Turismo sustent\u00e1vel\"],\"articleSection\":{\"0\":\"Amaz\u00f4nia\",\"1\":\"Braziliando\",\"2\":\"Diversidade e Inclus\u00e3o\",\"4\":\"Sustentabilidade\",\"5\":\"Turismo de Base Comunit\u00e1ria\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/braziliando.com\\\/2023\\\/12\\\/28\\\/retrospectiva-2023\\\/\",\"url\":\"https:\\\/\\\/braziliando.com\\\/2023\\\/12\\\/28\\\/retrospectiva-2023\\\/\",\"name\":\"Retrospectiva Braziliando 2023 - Braziliando\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/braziliando.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/braziliando.com\\\/2023\\\/12\\\/28\\\/retrospectiva-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/braziliando.com\\\/2023\\\/12\\\/28\\\/retrospectiva-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/braziliando.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Artes-SiteE-mail-mkt_Easy-Resize.com_.jpg\",\"datePublished\":\"2023-12-28T15:59:45+00:00\",\"dateModified\":\"2023-12-28T15:59:46+00:00\",\"description\":\"Vem conferir a Retrospectiva de 2023, celebrar com a gente o encerramento deste ciclo e renovar os votos para o pr\u00f3ximo ano.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/braziliando.com\\\/2023\\\/12\\\/28\\\/retrospectiva-2023\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/braziliando.com\\\/2023\\\/12\\\/28\\\/retrospectiva-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/braziliando.com\\\/2023\\\/12\\\/28\\\/retrospectiva-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/braziliando.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Artes-SiteE-mail-mkt_Easy-Resize.com_.jpg\",\"contentUrl\":\"https:\\\/\\\/braziliando.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Artes-SiteE-mail-mkt_Easy-Resize.com_.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/braziliando.com\\\/2023\\\/12\\\/28\\\/retrospectiva-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/braziliando.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retrospectiva Braziliando 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/braziliando.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/braziliando.com\\\/en\\\/\",\"name\":\"Braziliando - Viagens aut\u00eanticas e transformadoras\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/braziliando.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/braziliando.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/braziliando.com\\\/en\\\/#organization\",\"name\":\"Braziliando\",\"url\":\"https:\\\/\\\/braziliando.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/braziliando.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/braziliando.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Logo-BRDO-atualizada-fundo-transparente.png\",\"contentUrl\":\"https:\\\/\\\/braziliando.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Logo-BRDO-atualizada-fundo-transparente.png\",\"width\":452,\"height\":262,\"caption\":\"Braziliando\"},\"image\":{\"@id\":\"https:\\\/\\\/braziliando.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/braziliando\\\/\",\"https:\\\/\\\/www.instagram.com\\\/brazilian.do\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/braziliando.com\\\/en\\\/#\\\/schema\\\/person\\\/03deb579256404d78a2b7c1ae1ffa7e6\",\"name\":\"Braziliando\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retrospectiva Braziliando 2023 - Braziliando","description":"Vem conferir a Retrospectiva de 2023, celebrar com a gente o encerramento deste ciclo e renovar os votos para o pr\u00f3ximo ano.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/braziliando.com\/pt\/2023\/12\/28\/retrospectiva-2023\/","og_locale":"pt_BR","og_type":"article","og_title":"Retrospectiva Braziliando 2023 - Braziliando","og_description":"Vem conferir a Retrospectiva de 2023, celebrar com a gente o encerramento deste ciclo e renovar os votos para o pr\u00f3ximo ano.","og_url":"https:\/\/braziliando.com\/pt\/2023\/12\/28\/retrospectiva-2023\/","og_site_name":"Braziliando","article_publisher":"https:\/\/www.facebook.com\/braziliando\/","article_published_time":"2023-12-28T15:59:45+00:00","article_modified_time":"2023-12-28T15:59:46+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/braziliando.com\/wp-content\/uploads\/2023\/12\/Artes-SiteE-mail-mkt_Easy-Resize.com_.jpg","type":"image\/jpeg"}],"author":"Braziliando","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Braziliando","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/braziliando.com\/2023\/12\/28\/retrospectiva-2023\/#article","isPartOf":{"@id":"https:\/\/braziliando.com\/2023\/12\/28\/retrospectiva-2023\/"},"author":{"name":"Braziliando","@id":"https:\/\/braziliando.com\/en\/#\/schema\/person\/03deb579256404d78a2b7c1ae1ffa7e6"},"headline":"Retrospectiva Braziliando 2023","datePublished":"2023-12-28T15:59:45+00:00","dateModified":"2023-12-28T15:59:46+00:00","mainEntityOfPage":{"@id":"https:\/\/braziliando.com\/2023\/12\/28\/retrospectiva-2023\/"},"wordCount":893,"publisher":{"@id":"https:\/\/braziliando.com\/en\/#organization"},"image":{"@id":"https:\/\/braziliando.com\/2023\/12\/28\/retrospectiva-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/braziliando.com\/wp-content\/uploads\/2023\/12\/Artes-SiteE-mail-mkt_Easy-Resize.com_.jpg","keywords":["Amaz\u00f4nia","comunidade tradicional","diversidade","ind\u00edgenas","Turismo sustent\u00e1vel"],"articleSection":{"0":"Amaz\u00f4nia","1":"Braziliando","2":"Diversidade e Inclus\u00e3o","4":"Sustentabilidade","5":"Turismo de Base Comunit\u00e1ria"},"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/braziliando.com\/2023\/12\/28\/retrospectiva-2023\/","url":"https:\/\/braziliando.com\/2023\/12\/28\/retrospectiva-2023\/","name":"Retrospectiva Braziliando 2023 - Braziliando","isPartOf":{"@id":"https:\/\/braziliando.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/braziliando.com\/2023\/12\/28\/retrospectiva-2023\/#primaryimage"},"image":{"@id":"https:\/\/braziliando.com\/2023\/12\/28\/retrospectiva-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/braziliando.com\/wp-content\/uploads\/2023\/12\/Artes-SiteE-mail-mkt_Easy-Resize.com_.jpg","datePublished":"2023-12-28T15:59:45+00:00","dateModified":"2023-12-28T15:59:46+00:00","description":"Vem conferir a Retrospectiva de 2023, celebrar com a gente o encerramento deste ciclo e renovar os votos para o pr\u00f3ximo ano.","breadcrumb":{"@id":"https:\/\/braziliando.com\/2023\/12\/28\/retrospectiva-2023\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/braziliando.com\/2023\/12\/28\/retrospectiva-2023\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/braziliando.com\/2023\/12\/28\/retrospectiva-2023\/#primaryimage","url":"https:\/\/braziliando.com\/wp-content\/uploads\/2023\/12\/Artes-SiteE-mail-mkt_Easy-Resize.com_.jpg","contentUrl":"https:\/\/braziliando.com\/wp-content\/uploads\/2023\/12\/Artes-SiteE-mail-mkt_Easy-Resize.com_.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/braziliando.com\/2023\/12\/28\/retrospectiva-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/braziliando.com\/"},{"@type":"ListItem","position":2,"name":"Retrospectiva Braziliando 2023"}]},{"@type":"WebSite","@id":"https:\/\/braziliando.com\/en\/#website","url":"https:\/\/braziliando.com\/en\/","name":"Braziliando - Viagens aut\u00eanticas e transformadoras","description":"","publisher":{"@id":"https:\/\/braziliando.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/braziliando.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/braziliando.com\/en\/#organization","name":"Braziliando","url":"https:\/\/braziliando.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/braziliando.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/braziliando.com\/wp-content\/uploads\/2019\/10\/Logo-BRDO-atualizada-fundo-transparente.png","contentUrl":"https:\/\/braziliando.com\/wp-content\/uploads\/2019\/10\/Logo-BRDO-atualizada-fundo-transparente.png","width":452,"height":262,"caption":"Braziliando"},"image":{"@id":"https:\/\/braziliando.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/braziliando\/","https:\/\/www.instagram.com\/brazilian.do\/"]},{"@type":"Person","@id":"https:\/\/braziliando.com\/en\/#\/schema\/person\/03deb579256404d78a2b7c1ae1ffa7e6","name":"Braziliando"}]}},"_links":{"self":[{"href":"https:\/\/braziliando.com\/pt\/wp-json\/wp\/v2\/posts\/6162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/braziliando.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/braziliando.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/braziliando.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/braziliando.com\/pt\/wp-json\/wp\/v2\/comments?post=6162"}],"version-history":[{"count":8,"href":"https:\/\/braziliando.com\/pt\/wp-json\/wp\/v2\/posts\/6162\/revisions"}],"predecessor-version":[{"id":6172,"href":"https:\/\/braziliando.com\/pt\/wp-json\/wp\/v2\/posts\/6162\/revisions\/6172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/braziliando.com\/pt\/wp-json\/wp\/v2\/media\/6170"}],"wp:attachment":[{"href":"https:\/\/braziliando.com\/pt\/wp-json\/wp\/v2\/media?parent=6162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/braziliando.com\/pt\/wp-json\/wp\/v2\/categories?post=6162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/braziliando.com\/pt\/wp-json\/wp\/v2\/tags?post=6162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}